{"id":1302,"date":"2025-06-27T10:24:26","date_gmt":"2025-06-27T09:24:26","guid":{"rendered":"https:\/\/woodahome.es\/producto\/soporte-para-llaves\/"},"modified":"2025-06-27T10:24:29","modified_gmt":"2025-06-27T09:24:29","slug":"soporte-para-llaves","status":"publish","type":"product","link":"https:\/\/woodahome.es\/en\/product\/soporte-para-llaves\/","title":{"rendered":"Soporte para llaves"},"content":{"rendered":"<p>Soporte para colgar llaves, sobres o notas.<\/p>\n<p>Realizado en madera de pino, las plantas est\u00e1n incluidas.<\/p>\n<p>Para sujetar las cartas el soporte dispone de un cinta el\u00e1stica negra que las sujeta.<\/p>\n<p>El marco cuadrado de fondo es de 30 x 30 cm. Y las varillas de pino para las llaves miden 25 cm.<\/p>\n<p>Puedes consultarnos disponibilidad de colores.<\/p>","protected":false},"excerpt":{"rendered":"<p>Soporte para colgar llaves, sobres o notas. Realizado en madera de pino, las plantas est\u00e1n incluidas. Para sujetar las cartas el soporte dispone de un cinta el\u00e1stica negra que las sujeta. El marco cuadrado de fondo es de 30 x 30 cm. Y las varillas de pino para las llaves miden 25 cm. Puedes consultarnos [&hellip;]<\/p>\n","protected":false},"featured_media":1546,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_brand":[],"product_cat":[88],"product_tag":[],"class_list":{"0":"post-1302","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-soportes-para-llaves","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-variable"},"_links":{"self":[{"href":"https:\/\/woodahome.es\/en\/wp-json\/wp\/v2\/product\/1302","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/woodahome.es\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/woodahome.es\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/woodahome.es\/en\/wp-json\/wp\/v2\/comments?post=1302"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/woodahome.es\/en\/wp-json\/wp\/v2\/media\/1546"}],"wp:attachment":[{"href":"https:\/\/woodahome.es\/en\/wp-json\/wp\/v2\/media?parent=1302"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/woodahome.es\/en\/wp-json\/wp\/v2\/product_brand?post=1302"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/woodahome.es\/en\/wp-json\/wp\/v2\/product_cat?post=1302"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/woodahome.es\/en\/wp-json\/wp\/v2\/product_tag?post=1302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}